{"id":119470,"date":"2019-12-24T20:20:46","date_gmt":"2019-12-24T19:20:46","guid":{"rendered":"https:\/\/zjarr.tv\/?p=119470"},"modified":"2019-12-24T19:12:22","modified_gmt":"2019-12-24T18:12:22","slug":"video-moti-i-keq-pushton-vloren-dallget-demtojne-anijet-e-peshkimit-ne-radhime","status":"publish","type":"post","link":"https:\/\/zjarr.tv\/en\/video-moti-i-keq-pushton-vloren-dallget-demtojne-anijet-e-peshkimit-ne-radhime\/","title":{"rendered":"VIDEO\/ MOTI I KEQ &#8216;PUSHTON&#8217; VLOR\u00cbN, DALLG\u00cbT D\u00cbMTOJN\u00cb ANIJET E PESHKIMIT N\u00cb RADHIM\u00cb"},"content":{"rendered":"<div class=\"youtube-embed\" data-video_id=\"LwU-Eq3f5O0\"><iframe loading=\"lazy\" title=\"MOTI I KEQ &#039;PUSHTON&#039; VLOR\u00cbN, DALLG\u00cbT D\u00cbMTOJN\u00cb ANIJET E PESHKIMIT N\u00cb RADHIM\u00cb\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/LwU-Eq3f5O0?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2013,"featured_media":106886,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198,241,1,235],"tags":[],"class_list":["post-119470","post","type-post","status-publish","format-standard","has-post-thumbnail","category-360-grade","category-aktualitet","category-uncategorized-sq","category-vendi"],"_links":{"self":[{"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/posts\/119470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/users\/2013"}],"replies":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/comments?post=119470"}],"version-history":[{"count":0,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/posts\/119470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/media\/106886"}],"wp:attachment":[{"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/media?parent=119470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/categories?post=119470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/tags?post=119470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}