{"id":7853,"date":"2015-10-24T22:16:19","date_gmt":"2015-10-24T20:16:19","guid":{"rendered":"http:\/\/zjarr.tv\/?p=7853"},"modified":"2015-10-25T19:55:41","modified_gmt":"2015-10-25T17:55:41","slug":"360-grade-shtyhet-tenderi-per-durres-kukes","status":"publish","type":"post","link":"https:\/\/zjarr.tv\/en\/360-grade-shtyhet-tenderi-per-durres-kukes\/","title":{"rendered":"360\u00b0 Grade &#8211; SHTYHET TENDERI P\u00cbR DURR\u00cbS \u2013 KUK\u00cbS"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"360\u00b0 Grade - SHTYHET TENDERI P\u00cbR DURR\u00cbS \u2013 KUK\u00cbS\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/YWDBN7q-jv8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Web: http:\/\/zjarr.tv\/<br \/>\nFacebook: http:\/\/ift.tt\/1Nj96ih<br \/>\nYoutube: https:\/\/youtube.com\/c\/ZjarrTelevizion<br \/>\ninstagram: http:\/\/ift.tt\/1KYE3Lm<\/p>","protected":false},"excerpt":{"rendered":"<p>Web: http:\/\/zjarr.tv\/ Facebook: http:\/\/ift.tt\/1Nj96ih Youtube: https:\/\/youtube.com\/c\/ZjarrTelevizion instagram: http:\/\/ift.tt\/1KYE3Lm<\/p>","protected":false},"author":2044,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[198],"tags":[238,237],"class_list":["post-7853","post","type-post","status-publish","format-video","category-360-grade","tag-360grade-zbardhi-zjarr-televizion","tag-youtube","post_format-post-format-video"],"_links":{"self":[{"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/posts\/7853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/users\/2044"}],"replies":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/comments?post=7853"}],"version-history":[{"count":0,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/posts\/7853\/revisions"}],"wp:attachment":[{"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/media?parent=7853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/categories?post=7853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zjarr.tv\/en\/wp-json\/wp\/v2\/tags?post=7853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}