{"id":119289,"date":"2019-12-24T08:40:05","date_gmt":"2019-12-24T07:40:05","guid":{"rendered":"https:\/\/zjarr.tv\/?p=119289"},"modified":"2019-12-23T18:51:51","modified_gmt":"2019-12-23T17:51:51","slug":"video-moti-24-dhjetor-2019","status":"publish","type":"post","link":"https:\/\/zjarr.tv\/sq\/video-moti-24-dhjetor-2019\/","title":{"rendered":"Video\/ Moti 24 Dhjetor 2019"},"content":{"rendered":"<div class=\"youtube-embed\" data-video_id=\"3U70NzbUZTM\"><iframe loading=\"lazy\" title=\"MOTI - 24 DHJETOR 2019\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/3U70NzbUZTM?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2013,"featured_media":56635,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[241,1,235],"tags":[],"class_list":["post-119289","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aktualitet","category-uncategorized-sq","category-vendi"],"_links":{"self":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/posts\/119289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/users\/2013"}],"replies":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/comments?post=119289"}],"version-history":[{"count":0,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/posts\/119289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/media\/56635"}],"wp:attachment":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/media?parent=119289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/categories?post=119289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/tags?post=119289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}