{"id":3628,"date":"2015-08-07T12:30:18","date_gmt":"2015-08-07T10:30:18","guid":{"rendered":"http:\/\/zjarr.tv\/?p=3628"},"modified":"2015-08-07T11:49:09","modified_gmt":"2015-08-07T09:49:09","slug":"360-grade-greqi-juncker-optimist-per-arritjen-e-nje-marreveshjeje-me-kreditoret-para-20-gushtit","status":"publish","type":"post","link":"https:\/\/zjarr.tv\/sq\/360-grade-greqi-juncker-optimist-per-arritjen-e-nje-marreveshjeje-me-kreditoret-para-20-gushtit\/","title":{"rendered":"360\u00b0 Grade -GREQI-JUNCKER OPTIMIST PER ARRITJEN E NJE MARREVESHJEJE ME KREDITORET PARA 20 GUSHTIT"},"content":{"rendered":"<p><a href=\"http:\/\/youtu.be\/E_H2LWBLkwA\">http:\/\/youtu.be\/E_H2LWBLkwA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2044,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198],"tags":[],"class_list":["post-3628","post","type-post","status-publish","format-standard","category-360-grade"],"_links":{"self":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/posts\/3628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/users\/2044"}],"replies":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/comments?post=3628"}],"version-history":[{"count":0,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/posts\/3628\/revisions"}],"wp:attachment":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/media?parent=3628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/categories?post=3628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/tags?post=3628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}