{"id":83131,"date":"2019-05-09T15:17:18","date_gmt":"2019-05-09T13:17:18","guid":{"rendered":"https:\/\/zjarr.tv\/?p=83131"},"modified":"2019-05-09T15:17:18","modified_gmt":"2019-05-09T13:17:18","slug":"dita-e-europes-berisha-kombet-aspirojne-integrimin","status":"publish","type":"post","link":"https:\/\/zjarr.tv\/sq\/dita-e-europes-berisha-kombet-aspirojne-integrimin\/","title":{"rendered":"Dita e Europ\u00ebs\/ Berisha:  Kombet aspirojn\u00eb integrimin"},"content":{"rendered":"<p>Ish-kryeministri Sali Berisha shkruan se 9 Maji, \u00ebsht\u00eb dita ku kombet e vendeve an\u00ebtar\u00eb aspirojn\u00eb integrimin europian dhe kremtojn\u00eb themelimin e BE-s\u00eb, mrekullis\u00eb s\u00eb paqes, liris\u00eb, siguris\u00eb dhe begatis\u00eb.<\/p>\n<p>P\u00ebrmes nj\u00eb postimi n\u00eb \u201cFacebook\u201d, Berisha ndalet dhe te Shqip\u00ebria, nd\u00ebrsa e cil\u00ebson si kombin me mb\u00ebshtetjen m\u00eb t\u00eb madhe n\u00eb aspirat\u00ebn e fuqishme t\u00eb integrimit n\u00eb BE.<\/p>\n<p>\u201cSot dita e Europes!<\/p>\n<p>Miq, sot kombet e vendeve anetare dhe te gjithe ata qe aspirojne integrimin europian kremtojne pervjetorin e themelimit e Bashkmit Europian, mrekullise me te madhe te paqes, sigurise, lirise dhe begatise ne tere historine e Europes.<\/p>\n<p>Ne shqiptaret, ne kete dite vijme si kombi me mbeshtetjen me te madhe dhe aspiraten me te fuqishme per integrimin e Shqiperise ne BE.\u201d-shkruan Berisha.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ish-kryeministri Sali Berisha shkruan se 9 Maji, \u00ebsht\u00eb dita ku kombet e vendeve an\u00ebtar\u00eb aspirojn\u00eb integrimin europian dhe kremtojn\u00eb themelimin e BE-s\u00eb, mrekullis\u00eb s\u00eb paqes, liris\u00eb, siguris\u00eb dhe begatis\u00eb. P\u00ebrmes nj\u00eb postimi n\u00eb \u201cFacebook\u201d, Berisha ndalet dhe te Shqip\u00ebria, nd\u00ebrsa e cil\u00ebson si kombin me mb\u00ebshtetjen m\u00eb t\u00eb madhe n\u00eb aspirat\u00ebn e fuqishme t\u00eb integrimit [&hellip;]<\/p>\n","protected":false},"author":2013,"featured_media":65486,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[241,235],"tags":[],"class_list":["post-83131","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aktualitet","category-vendi"],"_links":{"self":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/posts\/83131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/users\/2013"}],"replies":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/comments?post=83131"}],"version-history":[{"count":0,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/posts\/83131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/media\/65486"}],"wp:attachment":[{"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/media?parent=83131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/categories?post=83131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zjarr.tv\/sq\/wp-json\/wp\/v2\/tags?post=83131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}